{"id":1145,"date":"2019-03-27T16:49:41","date_gmt":"2019-03-27T21:49:41","guid":{"rendered":"http:\/\/74n.71b.mywebsitetransfer.com\/?p=1145"},"modified":"2023-09-05T14:33:01","modified_gmt":"2023-09-05T14:33:01","slug":"un-livre-pour-dire-merci","status":"publish","type":"post","link":"https:\/\/delphineplatten.com\/en\/2019\/03\/un-livre-pour-dire-merci\/","title":{"rendered":"Un livre pour dire merci !"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Cadeau de d\u00e9part<\/h2>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Cet automne, j&rsquo;ai eu la chance de travailler pour une grande compagnie qu\u00e9b\u00e9coise (je vous laisse reconnaitre le logo, pas tr\u00e8s difficile !). J&rsquo;ai \u00e9t\u00e9 contact\u00e9 par le service de la communication : une dirigeante quittait la compagnie et pour lui dire au revoir, beaucoup d&#8217;employ\u00e9s voulaient \u00e9crire quelques lignes de remerciement. <br>Mais une pile de courriels imprim\u00e9s, \u00e7a ne donne gu\u00e8re un bel objet qu&rsquo;on a envie d&rsquo;offrir et de conserver. Alors j&rsquo;ai \u00e9t\u00e9 charg\u00e9e de r\u00e9aliser un livre qui relie ensemble tous ces t\u00e9moignages, dans un mat\u00e9riau pr\u00e9cieux, avec un d\u00e9cor personnalis\u00e9 qui soit \u00e0 la fois \u00e9l\u00e9gant et moderne, \u00e0 l&rsquo;image de la personne cens\u00e9e le recevoir. C&rsquo;est toute la beaut\u00e9 de la reliure et du cartonnage : donner corps \u00e0 l&rsquo;intangible !<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"666\" src=\"http:\/\/delphineplatten.com\/wp-content\/uploads\/2019\/03\/Delphine_Platten-Decor-Videotron-1024x666.jpg\" alt=\"De\u0301cor Vide\u0301otron\" class=\"wp-image-3801\" srcset=\"https:\/\/delphineplatten.com\/wp-content\/uploads\/2019\/03\/Delphine_Platten-Decor-Videotron-1024x666.jpg 1024w, https:\/\/delphineplatten.com\/wp-content\/uploads\/2019\/03\/Delphine_Platten-Decor-Videotron-300x195.jpg 300w, https:\/\/delphineplatten.com\/wp-content\/uploads\/2019\/03\/Delphine_Platten-Decor-Videotron-768x499.jpg 768w, https:\/\/delphineplatten.com\/wp-content\/uploads\/2019\/03\/Delphine_Platten-Decor-Videotron-18x12.jpg 18w, https:\/\/delphineplatten.com\/wp-content\/uploads\/2019\/03\/Delphine_Platten-Decor-Videotron-600x390.jpg 600w, https:\/\/delphineplatten.com\/wp-content\/uploads\/2019\/03\/Delphine_Platten-Decor-Videotron.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">De la n\u00e9cessit\u00e9 d&rsquo;avoir une m\u00e9thode de travail adapt\u00e9e<\/h2>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Apr\u00e8s quelques \u00e9changes d&rsquo;images et d&rsquo;id\u00e9es par courriel, j&rsquo;ai eu quelques jours pour confectionner la reliure. Travailler avec des d\u00e9lais tr\u00e8s serr\u00e9s, c&rsquo;est une constante dans un atelier. On est en bout de chaine de travail et on voit souvent les p\u00e9riodes-tampon s&rsquo;amenuiser au fur et \u00e0 mesure que le projet franchit les \u00e9tapes. Rien d&rsquo;anormal ni de surprenant, et il faut savoir l&rsquo;anticiper. Pr\u00e9parer les mat\u00e9riaux d&rsquo;avance, confectionner d&rsquo;avance des \u00e9l\u00e9ments de d\u00e9cor qu&rsquo;on sera capable de rapporter ensuite, faire le titrage sur pi\u00e8ces de titre pour les faire d&rsquo;avance ou pendant une p\u00e9riode de mise en presse&#8230;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Une grande libert\u00e9 artistique !<\/h2>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">J&rsquo;ai eu la chance immense de travailler avec une personne qui m&rsquo;a fait confiance. Elle a approuv\u00e9 la direction esth\u00e9tique que je souhaitais prendre et m&rsquo;a ensuite laiss\u00e9 totalement libre. Une seule demande : reprendre les couleurs de la compagnie, jaune et noir, dans la version pr\u00e9cieuse : or et noir. <br><br>Comme nous \u00e9tions juste dans le temps, j&rsquo;ai pris le parti de faire un d\u00e9cor en cuvette, que je pouvais pr\u00e9parer d&rsquo;avance. J&rsquo;ai proc\u00e9d\u00e9 \u00e0 une composition du logo de la compagnie, en collage de cuirs dor\u00e9s, vachette et serpent, avec une incrustation \u00e0 niveau en buffle noir, le cuir qui sera repris pour la reliure elle-m\u00eame. <\/p>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Une fois l&rsquo;impression livr\u00e9e, j&rsquo;ai r\u00e9alis\u00e9 une reliure coll\u00e9e endoss\u00e9e, pour lui donner cet aspect haut-de gamme de la reliure sans gorge. La reliure est un plein cuir de buffle noir, tr\u00e8s textur\u00e9. <br>Dans le m\u00eame esprit, nous avons choisi d&rsquo;ajouter des finitions en porc-velours d&rsquo;un noir tr\u00e8s dense sur les contre-plats, et d&rsquo;ajouter une touche lumineuse avec un papier japonais dor\u00e9 pour les volantes. <br>Il me restait \u00e0 placer le d\u00e9cor dans la fen\u00eatre cr\u00e9\u00e9e pour lui, et placer la pi\u00e8ce de titre sur le dos du livre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Une boite pour conserver le livre<\/h2>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Pour parfaire ce beau t\u00e9moignage, j&rsquo;ai fait une boite pour conserver le livre. <br>J&rsquo;ai fait une boite \u00e0 rubans grosgrain, tr\u00e8s simple, en belle toile noire, satin\u00e9e et moir\u00e9e, et finie du m\u00eame papier japonais dor\u00e9. J&rsquo;inclus toujours un certificat d&rsquo;authenticit\u00e9 dans mes projets : les clients font la d\u00e9marche de chercher une artisane qualifi\u00e9e qui leur fournira un travail sur-mesure, avec des mat\u00e9riaux de bonne qualit\u00e9 et c&rsquo;est ma fa\u00e7on de leur t\u00e9moigner du caract\u00e8re unique et du grand soin que j&rsquo;ai pris de leur projet.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"678\" src=\"https:\/\/delphineplatten.com\/wp-content\/uploads\/2023\/09\/Delphine-Platten-Certificat-authenticite-videotron-1024x678.jpg\" alt=\"Certificat d'authenticit\u00e9 Vid\u00e9otron\" class=\"wp-image-4023\" srcset=\"https:\/\/delphineplatten.com\/wp-content\/uploads\/2023\/09\/Delphine-Platten-Certificat-authenticite-videotron-1024x678.jpg 1024w, https:\/\/delphineplatten.com\/wp-content\/uploads\/2023\/09\/Delphine-Platten-Certificat-authenticite-videotron-300x199.jpg 300w, https:\/\/delphineplatten.com\/wp-content\/uploads\/2023\/09\/Delphine-Platten-Certificat-authenticite-videotron-768x508.jpg 768w, https:\/\/delphineplatten.com\/wp-content\/uploads\/2023\/09\/Delphine-Platten-Certificat-authenticite-videotron-18x12.jpg 18w, https:\/\/delphineplatten.com\/wp-content\/uploads\/2023\/09\/Delphine-Platten-Certificat-authenticite-videotron-600x397.jpg 600w, https:\/\/delphineplatten.com\/wp-content\/uploads\/2023\/09\/Delphine-Platten-Certificat-authenticite-videotron.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Certificat d&rsquo;authenticit\u00e9<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez un projet corporatif \u00e0 mener \u00e0 bien, pour un d\u00e9part au sein de votre entreprise, ou pour t\u00e9moigner \u00e0 un employ\u00e9 la qualit\u00e9 du travail qu&rsquo;il accomplit, <a href=\"mailto:atelierdelphineplatten@gmail.com\">n&rsquo;h\u00e9sitez pas \u00e0 me contacte<\/a>r : nous pourrons discuter de toutes les possibilit\u00e9s qui s&rsquo;offrent \u00e0 nous et je vous ferai parvenir un devis dans les jours suivants.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cadeau de d\u00e9part Cet automne, j&rsquo;ai eu la chance de travailler pour une grande compagnie qu\u00e9b\u00e9coise (je vous laisse reconnaitre le logo, pas tr\u00e8s difficile !). J&rsquo;ai \u00e9t\u00e9 contact\u00e9 par le service de la communication : une dirigeante quittait la&hellip; <a class=\"more-link\" href=\"https:\/\/delphineplatten.com\/en\/2019\/03\/un-livre-pour-dire-merci\/\">Continuer \u00e0 lire&#8230;<\/a><\/p>","protected":false},"author":1,"featured_media":4021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[148],"tags":[176],"class_list":["post-1145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projet-sur-mesure","tag-videotron","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un livre pour dire merci ! | Delphine Platten<\/title>\n<meta name=\"description\" content=\"Suivez l&#039;actualit\u00e9 de l&#039;Atelier Delphine Platten. Nouveaux cours, projets sur-mesure, techniques, restez connect\u00e9s et explorez l&#039;univers de la reliure et de la restauration d&#039;ouvrages\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/delphineplatten.com\/en\/2019\/03\/un-livre-pour-dire-merci\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un livre pour dire merci ! | Delphine Platten\" \/>\n<meta property=\"og:description\" content=\"Suivez l&#039;actualit\u00e9 de l&#039;Atelier Delphine Platten. Nouveaux cours, projets sur-mesure, techniques, restez connect\u00e9s et explorez l&#039;univers de la reliure et de la restauration d&#039;ouvrages\" \/>\n<meta property=\"og:url\" content=\"https:\/\/delphineplatten.com\/en\/2019\/03\/un-livre-pour-dire-merci\/\" \/>\n<meta property=\"og:site_name\" content=\"Delphine Platten\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DelphinePlattenReliure\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/DelphinePlattenReliure\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-27T21:49:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-05T14:33:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/delphineplatten.com\/wp-content\/uploads\/2019\/03\/Delphine-Platten-Boite-a-ruban-Videotron.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"786\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Delphine Platten\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Delphine Platten\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/2019\\\/03\\\/un-livre-pour-dire-merci\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/2019\\\/03\\\/un-livre-pour-dire-merci\\\/\"},\"author\":{\"name\":\"Delphine Platten\",\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/#\\\/schema\\\/person\\\/6cfffec4df5befcb81d26bf43624177a\"},\"headline\":\"Un livre pour dire merci !\",\"datePublished\":\"2019-03-27T21:49:41+00:00\",\"dateModified\":\"2023-09-05T14:33:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/2019\\\/03\\\/un-livre-pour-dire-merci\\\/\"},\"wordCount\":680,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/2019\\\/03\\\/un-livre-pour-dire-merci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/delphineplatten.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Delphine-Platten-Boite-a-ruban-Videotron.jpg\",\"keywords\":[\"Vid\u00e9otron\"],\"articleSection\":[\"Projet sur-mesure\"],\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/delphineplatten.com\\\/2019\\\/03\\\/un-livre-pour-dire-merci\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/2019\\\/03\\\/un-livre-pour-dire-merci\\\/\",\"url\":\"https:\\\/\\\/delphineplatten.com\\\/2019\\\/03\\\/un-livre-pour-dire-merci\\\/\",\"name\":\"Un livre pour dire merci ! | Delphine Platten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/2019\\\/03\\\/un-livre-pour-dire-merci\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/2019\\\/03\\\/un-livre-pour-dire-merci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/delphineplatten.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Delphine-Platten-Boite-a-ruban-Videotron.jpg\",\"datePublished\":\"2019-03-27T21:49:41+00:00\",\"dateModified\":\"2023-09-05T14:33:01+00:00\",\"description\":\"Suivez l'actualit\u00e9 de l'Atelier Delphine Platten. Nouveaux cours, projets sur-mesure, techniques, restez connect\u00e9s et explorez l'univers de la reliure et de la restauration d'ouvrages\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/2019\\\/03\\\/un-livre-pour-dire-merci\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/delphineplatten.com\\\/2019\\\/03\\\/un-livre-pour-dire-merci\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/2019\\\/03\\\/un-livre-pour-dire-merci\\\/#primaryimage\",\"url\":\"https:\\\/\\\/delphineplatten.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Delphine-Platten-Boite-a-ruban-Videotron.jpg\",\"contentUrl\":\"https:\\\/\\\/delphineplatten.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Delphine-Platten-Boite-a-ruban-Videotron.jpg\",\"width\":1200,\"height\":786,\"caption\":\"Boi\u0302te a\u0300 rubans Vide\u0301otron\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/2019\\\/03\\\/un-livre-pour-dire-merci\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/delphineplatten.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un livre pour dire merci !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/#website\",\"url\":\"https:\\\/\\\/delphineplatten.com\\\/\",\"name\":\"Delphine Platten\",\"description\":\"Atelier de reliure moderne\",\"publisher\":{\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/delphineplatten.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/#organization\",\"name\":\"Delphine Platten\",\"url\":\"https:\\\/\\\/delphineplatten.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/delphineplatten.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Delphine_Platten_Logo.png\",\"contentUrl\":\"https:\\\/\\\/delphineplatten.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Delphine_Platten_Logo.png\",\"width\":320,\"height\":320,\"caption\":\"Delphine Platten\"},\"image\":{\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DelphinePlattenReliure\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/delphineplatten.com\\\/#\\\/schema\\\/person\\\/6cfffec4df5befcb81d26bf43624177a\",\"name\":\"Delphine Platten\",\"sameAs\":[\"https:\\\/\\\/delphineplatten.com\",\"https:\\\/\\\/www.facebook.com\\\/DelphinePlattenReliure\",\"https:\\\/\\\/www.instagram.com\\\/delphineplattenreliure\\\/?hl=fr\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/delphineplatten\\\/\"],\"url\":\"https:\\\/\\\/delphineplatten.com\\\/en\\\/author\\\/dpreliure01\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un livre pour dire merci ! | Delphine Platten","description":"Suivez l'actualit\u00e9 de l'Atelier Delphine Platten. Nouveaux cours, projets sur-mesure, techniques, restez connect\u00e9s et explorez l'univers de la reliure et de la restauration d'ouvrages","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/delphineplatten.com\/en\/2019\/03\/un-livre-pour-dire-merci\/","og_locale":"en_US","og_type":"article","og_title":"Un livre pour dire merci ! | Delphine Platten","og_description":"Suivez l'actualit\u00e9 de l'Atelier Delphine Platten. Nouveaux cours, projets sur-mesure, techniques, restez connect\u00e9s et explorez l'univers de la reliure et de la restauration d'ouvrages","og_url":"https:\/\/delphineplatten.com\/en\/2019\/03\/un-livre-pour-dire-merci\/","og_site_name":"Delphine Platten","article_publisher":"https:\/\/www.facebook.com\/DelphinePlattenReliure","article_author":"https:\/\/www.facebook.com\/DelphinePlattenReliure","article_published_time":"2019-03-27T21:49:41+00:00","article_modified_time":"2023-09-05T14:33:01+00:00","og_image":[{"width":1200,"height":786,"url":"https:\/\/delphineplatten.com\/wp-content\/uploads\/2019\/03\/Delphine-Platten-Boite-a-ruban-Videotron.jpg","type":"image\/jpeg"}],"author":"Delphine Platten","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Delphine Platten","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/delphineplatten.com\/2019\/03\/un-livre-pour-dire-merci\/#article","isPartOf":{"@id":"https:\/\/delphineplatten.com\/2019\/03\/un-livre-pour-dire-merci\/"},"author":{"name":"Delphine Platten","@id":"https:\/\/delphineplatten.com\/#\/schema\/person\/6cfffec4df5befcb81d26bf43624177a"},"headline":"Un livre pour dire merci !","datePublished":"2019-03-27T21:49:41+00:00","dateModified":"2023-09-05T14:33:01+00:00","mainEntityOfPage":{"@id":"https:\/\/delphineplatten.com\/2019\/03\/un-livre-pour-dire-merci\/"},"wordCount":680,"commentCount":0,"publisher":{"@id":"https:\/\/delphineplatten.com\/#organization"},"image":{"@id":"https:\/\/delphineplatten.com\/2019\/03\/un-livre-pour-dire-merci\/#primaryimage"},"thumbnailUrl":"https:\/\/delphineplatten.com\/wp-content\/uploads\/2019\/03\/Delphine-Platten-Boite-a-ruban-Videotron.jpg","keywords":["Vid\u00e9otron"],"articleSection":["Projet sur-mesure"],"inLanguage":"en-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/delphineplatten.com\/2019\/03\/un-livre-pour-dire-merci\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/delphineplatten.com\/2019\/03\/un-livre-pour-dire-merci\/","url":"https:\/\/delphineplatten.com\/2019\/03\/un-livre-pour-dire-merci\/","name":"Un livre pour dire merci ! | Delphine Platten","isPartOf":{"@id":"https:\/\/delphineplatten.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/delphineplatten.com\/2019\/03\/un-livre-pour-dire-merci\/#primaryimage"},"image":{"@id":"https:\/\/delphineplatten.com\/2019\/03\/un-livre-pour-dire-merci\/#primaryimage"},"thumbnailUrl":"https:\/\/delphineplatten.com\/wp-content\/uploads\/2019\/03\/Delphine-Platten-Boite-a-ruban-Videotron.jpg","datePublished":"2019-03-27T21:49:41+00:00","dateModified":"2023-09-05T14:33:01+00:00","description":"Suivez l'actualit\u00e9 de l'Atelier Delphine Platten. Nouveaux cours, projets sur-mesure, techniques, restez connect\u00e9s et explorez l'univers de la reliure et de la restauration d'ouvrages","breadcrumb":{"@id":"https:\/\/delphineplatten.com\/2019\/03\/un-livre-pour-dire-merci\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/delphineplatten.com\/2019\/03\/un-livre-pour-dire-merci\/"]}]},{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/delphineplatten.com\/2019\/03\/un-livre-pour-dire-merci\/#primaryimage","url":"https:\/\/delphineplatten.com\/wp-content\/uploads\/2019\/03\/Delphine-Platten-Boite-a-ruban-Videotron.jpg","contentUrl":"https:\/\/delphineplatten.com\/wp-content\/uploads\/2019\/03\/Delphine-Platten-Boite-a-ruban-Videotron.jpg","width":1200,"height":786,"caption":"Boi\u0302te a\u0300 rubans Vide\u0301otron"},{"@type":"BreadcrumbList","@id":"https:\/\/delphineplatten.com\/2019\/03\/un-livre-pour-dire-merci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/delphineplatten.com\/"},{"@type":"ListItem","position":2,"name":"Un livre pour dire merci !"}]},{"@type":"WebSite","@id":"https:\/\/delphineplatten.com\/#website","url":"https:\/\/delphineplatten.com\/","name":"Delphine Platten","description":"Atelier de reliure moderne","publisher":{"@id":"https:\/\/delphineplatten.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/delphineplatten.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/delphineplatten.com\/#organization","name":"Delphine Platten","url":"https:\/\/delphineplatten.com\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/delphineplatten.com\/#\/schema\/logo\/image\/","url":"https:\/\/delphineplatten.com\/wp-content\/uploads\/2023\/06\/Delphine_Platten_Logo.png","contentUrl":"https:\/\/delphineplatten.com\/wp-content\/uploads\/2023\/06\/Delphine_Platten_Logo.png","width":320,"height":320,"caption":"Delphine Platten"},"image":{"@id":"https:\/\/delphineplatten.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DelphinePlattenReliure"]},{"@type":"Person","@id":"https:\/\/delphineplatten.com\/#\/schema\/person\/6cfffec4df5befcb81d26bf43624177a","name":"Delphine Platten","sameAs":["https:\/\/delphineplatten.com","https:\/\/www.facebook.com\/DelphinePlattenReliure","https:\/\/www.instagram.com\/delphineplattenreliure\/?hl=fr","https:\/\/www.linkedin.com\/in\/delphineplatten\/"],"url":"https:\/\/delphineplatten.com\/en\/author\/dpreliure01\/"}]}},"_links":{"self":[{"href":"https:\/\/delphineplatten.com\/en\/wp-json\/wp\/v2\/posts\/1145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delphineplatten.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/delphineplatten.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/delphineplatten.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/delphineplatten.com\/en\/wp-json\/wp\/v2\/comments?post=1145"}],"version-history":[{"count":3,"href":"https:\/\/delphineplatten.com\/en\/wp-json\/wp\/v2\/posts\/1145\/revisions"}],"predecessor-version":[{"id":4024,"href":"https:\/\/delphineplatten.com\/en\/wp-json\/wp\/v2\/posts\/1145\/revisions\/4024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/delphineplatten.com\/en\/wp-json\/wp\/v2\/media\/4021"}],"wp:attachment":[{"href":"https:\/\/delphineplatten.com\/en\/wp-json\/wp\/v2\/media?parent=1145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/delphineplatten.com\/en\/wp-json\/wp\/v2\/categories?post=1145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/delphineplatten.com\/en\/wp-json\/wp\/v2\/tags?post=1145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}